{"id":12266,"date":"2021-04-03T15:35:45","date_gmt":"2021-04-03T14:35:45","guid":{"rendered":"https:\/\/www.v-gaertner.at\/WP\/gardening-tips\/kuchengarten-copy\/"},"modified":"2021-04-03T15:49:22","modified_gmt":"2021-04-03T14:49:22","slug":"kuchengarten-copy","status":"publish","type":"gardening-tips","link":"https:\/\/www.v-gaertner.at\/WP\/gardening-tips\/kuchengarten-copy\/","title":{"rendered":"Wildhecken und Wildobst"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][\/vc_row][vc_column][\/vc_column][vc_column_text]Das Jahr 2021 steht in Vorarlberg ganz im Zeichen von Wildhecken. Verschiedene Organisationen im Land haben sich unter F\u00fchrung des Verbandes Obst- &amp; Gartenkultur und der Landwirtschaftskammer Vorarlberg diesen Thema gewidmet. Entnehmen Sie aus beiliegender Brosch\u00fcre das vielf\u00e4ltige Informations- und Veranstaltungsprogramm dazu. Zus\u00e4tzlich bieten mehrere Vorarlberger Baumschulen sowie der Landesforstgarten schwerpunktm\u00e4\u00dfig Wildgeh\u00f6lze f\u00fcr ihren Garten an.<\/p>\n<p>&nbsp;<\/p>\n<p>Weiterf\u00fchrenden Informationen zum Herunterladen finden sie unter diesen Links:<\/p>\n<ul>\n<li>Wildobstbrosch\u00fcren und Sortenbl\u00e4tter:<br \/>\n<a href=\"http:\/\/www.ogv.at\/detail\/ogv-landesverband\/die-neue-broschuere-rund-um-die-heimischen-wildhecken-ist-da-1173\">OGV Vorarlberg<\/a> oder <a href=\"https:\/\/vbg.lko.at\/downloads+2500++1302707\">Landwirtschaftskammer Vorarlberg<\/a><\/li>\n<li>Brosch\u00fcren des Landes Vorarlberg: <a href=\"https:\/\/naturvielfalt.at\/downloads\">Naturvielfalt Vorarlberg<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column][\/vc_column][vc_column css=&#8220;. Vc_custom_1598896539857 {margin-top: 15px! Important ;}&#8220;][\/vc_column]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][\/vc_row][vc_column][\/vc_column][vc_column_text]Das Jahr 2021 steht in Vorarlberg ganz im Zeichen von Wildhecken. Verschiedene Organisationen im Land haben sich unter F\u00fchrung des Verbandes Obst- &amp; Gartenkultur und der Landwirtschaftskammer Vorarlberg diesen Thema gewidmet. Entnehmen Sie aus beiliegender Brosch\u00fcre das vielf\u00e4ltige Informations- und Veranstaltungsprogramm dazu. Zus\u00e4tzlich bieten mehrere Vorarlberger Baumschulen sowie der Landesforstgarten schwerpunktm\u00e4\u00dfig Wildgeh\u00f6lze f\u00fcr ihren Garten [&hellip;]<\/p>\n","protected":false},"featured_media":12257,"template":"","class_list":["post-12266","gardening-tips","type-gardening-tips","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.v-gaertner.at\/WP\/wp-json\/wp\/v2\/gardening-tips\/12266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.v-gaertner.at\/WP\/wp-json\/wp\/v2\/gardening-tips"}],"about":[{"href":"https:\/\/www.v-gaertner.at\/WP\/wp-json\/wp\/v2\/types\/gardening-tips"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.v-gaertner.at\/WP\/wp-json\/wp\/v2\/media\/12257"}],"wp:attachment":[{"href":"https:\/\/www.v-gaertner.at\/WP\/wp-json\/wp\/v2\/media?parent=12266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}